{"id":40893,"date":"2020-07-08T14:38:14","date_gmt":"2020-07-08T12:38:14","guid":{"rendered":"https:\/\/dellaroveregioielli.it\/non class\u00e9\/collier-deux-brins-en-amazonite\/"},"modified":"2020-07-08T14:38:14","modified_gmt":"2020-07-08T12:38:14","slug":"collier-deux-brins-en-amazonite","status":"publish","type":"product","link":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/","title":{"rendered":"Collier deux brins en Amazonite"},"content":{"rendered":"<p>Collier court compos\u00e9 de deux rondelles d&#8217;Amazonite, avec fermoir maxi push en argent 925\u2030 rhodi\u00e9. Fabriqu\u00e9 en Italie.<\/p>\n<p><em>Longueur : 52 cm<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Collier court compos\u00e9 de deux rondelles d&#8217;Amazonite, avec fermoir maxi push en argent 925\u2030 rhodi\u00e9. Fabriqu\u00e9 en Italie. Longueur : 52 cm<\/p>\n","protected":false},"featured_media":40898,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[757,707,706,708],"product_tag":[802],"class_list":["post-40893","product","type-product","status-publish","has-post-thumbnail","product_cat-bijoux-en-argent","product_cat-bijoux-en-pierres-dures","product_cat-colliers-pour-femmes","product_cat-colliers-de-pierres-dures","product_tag-nouveautes-2025-2026","first","instock","sale","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collier deux brins en Amazonite - Della Rovere<\/title>\n<meta name=\"description\" content=\"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collier deux brins en Amazonite - Della Rovere\" \/>\n<meta property=\"og:description\" content=\"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/\" \/>\n<meta property=\"og:site_name\" content=\"Della Rovere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2025\/10\/EC127.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/\",\"url\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/\",\"name\":\"Collier deux brins en Amazonite - Della Rovere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dellaroveregioielli.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EC127.jpg\",\"datePublished\":\"2020-07-08T12:38:14+00:00\",\"description\":\"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dellaroveregioielli.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EC127.jpg\",\"contentUrl\":\"https:\\\/\\\/dellaroveregioielli.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EC127.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Collier deux brins en Amazonite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/colliers-de-pierres-dures\\\/collier-deux-brins-en-amazonite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dellaroveregioielli.it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collier deux brins en Amazonite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/\",\"name\":\"Della Rovere\",\"description\":\"Gioielli in argento e pietre dure\",\"publisher\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#organization\",\"name\":\"Della Rovere\",\"url\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dellaroveregioielli.it\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dellarovere-completo.png\",\"contentUrl\":\"https:\\\/\\\/dellaroveregioielli.it\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dellarovere-completo.png\",\"width\":904,\"height\":199,\"caption\":\"Della Rovere\"},\"image\":{\"@id\":\"https:\\\/\\\/dellaroveregioielli.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collier deux brins en Amazonite - Della Rovere","description":"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/","og_locale":"fr_FR","og_type":"article","og_title":"Collier deux brins en Amazonite - Della Rovere","og_description":"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.","og_url":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/","og_site_name":"Della Rovere","og_image":[{"width":2000,"height":2000,"url":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2025\/10\/EC127.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/","url":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/","name":"Collier deux brins en Amazonite - Della Rovere","isPartOf":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/#primaryimage"},"image":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/#primaryimage"},"thumbnailUrl":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2025\/10\/EC127.jpg","datePublished":"2020-07-08T12:38:14+00:00","description":"Collier \u00e0 deux brins en amazonite. Produits artisanaux fabriqu\u00e9s en Italie. D\u00e9couvrez notre catalogue en ligne. Livraison rapide ! Coupon de r\u00e9duction pour le premier achat.","breadcrumb":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/#primaryimage","url":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2025\/10\/EC127.jpg","contentUrl":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2025\/10\/EC127.jpg","width":2000,"height":2000,"caption":"Collier deux brins en Amazonite"},{"@type":"BreadcrumbList","@id":"https:\/\/dellaroveregioielli.it\/fr\/colliers-de-pierres-dures\/collier-deux-brins-en-amazonite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/dellaroveregioielli.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dellaroveregioielli.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Collier deux brins en Amazonite"}]},{"@type":"WebSite","@id":"https:\/\/dellaroveregioielli.it\/fr\/#website","url":"https:\/\/dellaroveregioielli.it\/fr\/","name":"Della Rovere","description":"Gioielli in argento e pietre dure","publisher":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dellaroveregioielli.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dellaroveregioielli.it\/fr\/#organization","name":"Della Rovere","url":"https:\/\/dellaroveregioielli.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dellaroveregioielli.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2020\/08\/logo-dellarovere-completo.png","contentUrl":"https:\/\/dellaroveregioielli.it\/wp-content\/uploads\/2020\/08\/logo-dellarovere-completo.png","width":904,"height":199,"caption":"Della Rovere"},"image":{"@id":"https:\/\/dellaroveregioielli.it\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product\/40893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/comments?post=40893"}],"version-history":[{"count":0,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product\/40893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/media\/40898"}],"wp:attachment":[{"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/media?parent=40893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product_brand?post=40893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product_cat?post=40893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dellaroveregioielli.it\/fr\/wp-json\/wp\/v2\/product_tag?post=40893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}